{"id":1399,"date":"2021-04-21T16:28:14","date_gmt":"2021-04-21T16:28:14","guid":{"rendered":"https:\/\/cirice.hosting-em.store\/cms\/2021\/03\/11\/castellammare-allalba\/"},"modified":"2021-04-21T16:28:15","modified_gmt":"2021-04-21T16:28:15","slug":"castellammare-allalba","status":"publish","type":"post","link":"https:\/\/www.iconografiacittaeuropea.unina.it\/cms\/castellammare-allalba\/","title":{"rendered":"Castellammare all\u2019alba"},"content":{"rendered":"<p><img src=\/catalogo\/archivio_immagini\/CM 16.jpg \/><br \/>\n<!--more--><br \/>\nNel suggestivo dipinto, di cui si riportano il titolo e la data in basso a destra \u00abVu\u00eb de Castel:\/\u00e0 Mare, dans\/le Golf de Naples.\/ Ph. Hackert. \/ 1782\u00bb, l\u2019autore riprende la citt\u00e0 di Castellammare di Stabia all\u2019alba dal lato del porto con le spalle al golfo di Sorrento; \u00e8 probabile che il punto di vista fosse posto al di sotto della collina di Pozzano. Si tratta di uno dei primi quadri per Ferdinando IV. Scrive Goethe in proposito nel 1811: \u00abIntanto Hackert dovette promettere al re anche un grande dipinto di Castellammare, incluse le sue galeotte. Perci\u00f2 dovette fermarsi a Napoli pi\u00f9 a lungo per preparare gli studi necessari infatti bisognava fare tutto nel pieno rispetto dell\u2019arte di governare le navi. [\u2026] Verso la met\u00e0 di ottobre venne [a Caserta] anche l\u2019artista che present\u00f2 al re il grande dipinto a olio di Castellammare, accolto nel migliore dei modi\u00bb. Nella veduta \u00e8 possibile notare alcune navi ormeggiate, altre in arrivo e piccole barche di pescatori vicino alla riva. Del nucleo urbano, posto in secondo piano, sono visibili le strutture dei Cantieri navali e la porta della Fontana. [g.m.]<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[2],"tags":[],"_links":{"self":[{"href":"https:\/\/www.iconografiacittaeuropea.unina.it\/cms\/wp-json\/wp\/v2\/posts\/1399"}],"collection":[{"href":"https:\/\/www.iconografiacittaeuropea.unina.it\/cms\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.iconografiacittaeuropea.unina.it\/cms\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.iconografiacittaeuropea.unina.it\/cms\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.iconografiacittaeuropea.unina.it\/cms\/wp-json\/wp\/v2\/comments?post=1399"}],"version-history":[{"count":1,"href":"https:\/\/www.iconografiacittaeuropea.unina.it\/cms\/wp-json\/wp\/v2\/posts\/1399\/revisions"}],"predecessor-version":[{"id":4134,"href":"https:\/\/www.iconografiacittaeuropea.unina.it\/cms\/wp-json\/wp\/v2\/posts\/1399\/revisions\/4134"}],"wp:attachment":[{"href":"https:\/\/www.iconografiacittaeuropea.unina.it\/cms\/wp-json\/wp\/v2\/media?parent=1399"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.iconografiacittaeuropea.unina.it\/cms\/wp-json\/wp\/v2\/categories?post=1399"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.iconografiacittaeuropea.unina.it\/cms\/wp-json\/wp\/v2\/tags?post=1399"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}